{"id":9768,"date":"2021-03-25T14:42:55","date_gmt":"2021-03-25T13:42:55","guid":{"rendered":"https:\/\/titandizajn.com\/portfolio\/cozzy\/"},"modified":"2021-03-25T15:29:55","modified_gmt":"2021-03-25T14:29:55","slug":"cozzy","status":"publish","type":"portfolio","link":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/","title":{"rendered":"Cozzy"},"content":{"rendered":"<div id='av-layout-grid-1'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first  container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-1  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-2  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9638 avia-img-lazy-loading-not-9638 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1.jpg\" alt='' title='Cozzzy - Post 10 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-10-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-3  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:top; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock single-title '   itemprop=\"text\" ><h2>Post design for &#8220;Cozzy&#8221;<\/h2>\n<\/div><\/section>\n<\/div><\/div><\/div><div id='av-layout-grid-2'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-5  el_after_av_layout_row  el_before_av_layout_row  submenu-not-first container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-6  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-7  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9662 avia-img-lazy-loading-not-9662 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1.jpg\" alt='' title='Cozzzy - Post 1 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-8  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible right-to-left av-styling-    avia-builder-el-9  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9666 avia-img-lazy-loading-not-9666 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1.jpg\" alt='' title='Cozzzy - Post 2 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-2-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/p>\n<div id='av-layout-grid-3'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-10  el_after_av_layout_row  el_before_av_layout_row  submenu-not-first container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-11  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-12  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9670 avia-img-lazy-loading-not-9670 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1.jpg\" alt='' title='Cozzzy - Post 3 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-3-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-13  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible right-to-left av-styling-    avia-builder-el-14  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9674 avia-img-lazy-loading-not-9674 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1.jpg\" alt='' title='Cozzzy - Post 4 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-4-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div id='av-layout-grid-4'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-15  el_after_av_layout_row  el_before_av_layout_row  submenu-not-first container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-16  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-17  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9642 avia-img-lazy-loading-not-9642 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1.jpg\" alt='' title='Cozzzy - Post 5 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-5-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-18  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible right-to-left av-styling-    avia-builder-el-19  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9646 avia-img-lazy-loading-not-9646 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1.jpg\" alt='' title='Cozzzy - Post 6 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-6-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div id='av-layout-grid-5'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-20  el_after_av_layout_row  el_before_av_layout_row  submenu-not-first container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-21  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-22  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9650 avia-img-lazy-loading-not-9650 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1.jpg\" alt='' title='Cozzzy - Post 7 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-7-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-23  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible right-to-left av-styling-    avia-builder-el-24  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9654 avia-img-lazy-loading-not-9654 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1.jpg\" alt='' title='Cozzzy - Post 8 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-8-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<div id='av-layout-grid-6'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-25  el_after_av_layout_row  el_before_av_one_third  submenu-not-first container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-26  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-27  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-9658 avia-img-lazy-loading-not-9658 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1.jpg\" alt='' title='Cozzzy - Post 9 (800x600)' height=\"600\" width=\"800\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1.jpg 800w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1-600x450.jpg 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1-300x225.jpg 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1-768x576.jpg 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1-705x529.jpg 705w, https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-9-800x600-1-450x338.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-28  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><\/div><\/div>\n<\/div><div id='after_submenu_6'  class='main_color av_default_container_wrap container_wrap fullsize' style=' '  ><div class='container' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-9768'><div class='entry-content-wrapper clearfix'>\n<div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first  avia-builder-el-29  el_after_av_layout_row  el_before_av_one_third  avia-builder-el-first  \" style='border-radius:0px; '><\/div>\n<p><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding   avia-builder-el-30  el_after_av_one_third  el_before_av_one_third  \" style='border-radius:0px; '><div  class='av-social-sharing-box  avia-builder-el-31  avia-builder-el-no-sibling  '><div class='av-share-box'><h5 class='av-share-link-description av-no-toc '><\/p>\n<h4 style=\"text-align: center;\">Share This<\/h4>\n<h4><\/h5><ul class='av-share-box-list noLightbox'><li class='av-share-link av-social-link-facebook' ><a target=\"_blank\" aria-label=\"Condividi su Facebook\" href='https:\/\/www.facebook.com\/sharer.php?u=https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/&#038;t=Cozzy' aria-hidden='false' data-av_icon='\ue8f3' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Condividi su Facebook' rel=\"noopener\"><span class='avia_hidden_link_text'>Condividi su Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target=\"_blank\" aria-label=\"Condividi su Twitter\" href='https:\/\/twitter.com\/share?text=Cozzy&#038;url=https:\/\/titandizajn.com\/it\/?p=9768' aria-hidden='false' data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Condividi su Twitter' rel=\"noopener\"><span class='avia_hidden_link_text'>Condividi su Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-whatsapp' ><a target=\"_blank\" aria-label=\"Condividi su WhatsApp\" href='https:\/\/api.whatsapp.com\/send?text=https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/' aria-hidden='false' data-av_icon='\uf232' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Condividi su WhatsApp' rel=\"noopener\"><span class='avia_hidden_link_text'>Condividi su WhatsApp<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin' ><a target=\"_blank\" aria-label=\"Condividi su LinkedIn\" href='https:\/\/linkedin.com\/shareArticle?mini=true&#038;title=Cozzy&#038;url=https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/' aria-hidden='false' data-av_icon='\ue8fc' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Condividi su LinkedIn' rel=\"noopener\"><span class='avia_hidden_link_text'>Condividi su LinkedIn<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  aria-label=\"Condividi attraverso Mail\" href='mailto:?subject=Cozzy&#038;body=https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/' aria-hidden='false' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Condividi attraverso Mail'><span class='avia_hidden_link_text'>Condividi attraverso Mail<\/span><\/a><\/li><\/ul><\/div><\/div><\/div><\/h4>\n<div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding   avia-builder-el-32  el_after_av_one_third  avia-builder-el-last  \" style='border-radius:0px; '><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9724,"comment_status":"open","ping_status":"open","template":"","tags":[],"portfolio_entries":[139,135,140],"class_list":["post-9768","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-design-di-billboard","portfolio_entries-disegno-grafico","portfolio_entries-identita-visual"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cozzy - Titan Dizajn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cozzy - Titan Dizajn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/\" \/>\n<meta property=\"og:site_name\" content=\"Titan Dizajn\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-25T14:29:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-480x435-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/\",\"name\":\"Cozzy - Titan Dizajn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Cozzzy-Post-1-480x435-1.jpg\",\"datePublished\":\"2021-03-25T13:42:55+00:00\",\"dateModified\":\"2021-03-25T14:29:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Cozzzy-Post-1-480x435-1.jpg\",\"contentUrl\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Cozzzy-Post-1-480x435-1.jpg\",\"width\":480,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/portfolio\\\/cozzy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/titandizajn.com\\\/it\\\/pocetna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cozzy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/#website\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/\",\"name\":\"Titan Dizajn\",\"description\":\"Creative Agency\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/titandizajn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cozzy - Titan Dizajn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/","og_locale":"it_IT","og_type":"article","og_title":"Cozzy - Titan Dizajn","og_url":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/","og_site_name":"Titan Dizajn","article_modified_time":"2021-03-25T14:29:55+00:00","og_image":[{"width":480,"height":435,"url":"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-480x435-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/","url":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/","name":"Cozzy - Titan Dizajn","isPartOf":{"@id":"https:\/\/titandizajn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/#primaryimage"},"image":{"@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/#primaryimage"},"thumbnailUrl":"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-480x435-1.jpg","datePublished":"2021-03-25T13:42:55+00:00","dateModified":"2021-03-25T14:29:55+00:00","breadcrumb":{"@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/#primaryimage","url":"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-480x435-1.jpg","contentUrl":"https:\/\/titandizajn.com\/wp-content\/uploads\/2021\/03\/Cozzzy-Post-1-480x435-1.jpg","width":480,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/titandizajn.com\/it\/portfolio\/cozzy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/titandizajn.com\/it\/pocetna\/"},{"@type":"ListItem","position":2,"name":"Cozzy"}]},{"@type":"WebSite","@id":"https:\/\/titandizajn.com\/#website","url":"https:\/\/titandizajn.com\/","name":"Titan Dizajn","description":"Creative Agency","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/titandizajn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/portfolio\/9768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/comments?post=9768"}],"version-history":[{"count":2,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/portfolio\/9768\/revisions"}],"predecessor-version":[{"id":9773,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/portfolio\/9768\/revisions\/9773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/media\/9724"}],"wp:attachment":[{"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/media?parent=9768"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/tags?post=9768"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/titandizajn.com\/it\/wp-json\/wp\/v2\/portfolio_entries?post=9768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}