{"id":4041,"date":"2019-12-20T10:49:30","date_gmt":"2019-12-20T09:49:30","guid":{"rendered":"http:\/\/dev.titandizajn.com\/portfolio\/xenia-2"},"modified":"2023-10-12T09:35:34","modified_gmt":"2023-10-12T07:35:34","slug":"kuvana-jela","status":"publish","type":"portfolio","link":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/","title":{"rendered":"Kuvana jela"},"content":{"rendered":"<div id='av-layout-grid-1'  class='av-layout-grid-container entry-content-wrapper main_color av-flex-cells     avia-builder-el-0  el_before_av_one_third  avia-builder-el-first  container_wrap fullsize' style=' '  >\n<div class=\"flex_cell no_margin av_one_half  avia-builder-el-1  el_before_av_cell_one_half  avia-builder-el-first   \"  style='vertical-align:middle; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><div  class='avia-image-container avia_animated_image avia_animate_when_almost_visible left-to-right av-styling-    avia-builder-el-2  avia-builder-el-no-sibling  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-21628 avia-img-lazy-loading-not-21628 avia_image' src=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela.webp\" alt='' title='dizajn-ambalaze-gotova-jela' height=\"670\" width=\"960\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela.webp 960w, https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela-600x419.webp 600w, https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela-300x209.webp 300w, https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela-768x536.webp 768w, https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/02\/dizajn-ambalaze-gotova-jela-705x492.webp 705w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/div><\/div><\/div>\n<\/div><\/div><div class=\"flex_cell no_margin av_one_half  avia-builder-el-3  el_after_av_cell_one_half  avia-builder-el-last   \"  style='vertical-align:top; padding:35px 45px 35px 45px ; ' ><div class='flex_cell_inner' ><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock single-title '   itemprop=\"text\" ><h2>Verpackungsdesign f\u00fcr Swisslion-Takovo<\/h2>\n<\/div><\/section>\n<\/div><\/div><\/div><div id='after_submenu_1'  class='main_color av_default_container_wrap container_wrap fullsize' style=' '  ><div class='container' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4041'><div class='entry-content-wrapper clearfix'><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first  avia-builder-el-5  el_after_av_layout_row  el_before_av_one_third  avia-builder-el-first  \" style='border-radius:0px; '><\/div><\/p>\n<p><div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding   avia-builder-el-6  el_after_av_one_third  el_before_av_one_third  \" style='border-radius:0px; '><div  class='av-social-sharing-box  avia-builder-el-7  avia-builder-el-no-sibling  '><div class='av-share-box'><h5 class='av-share-link-description av-no-toc '><\/p>\n<h4 style=\"text-align: center;\">Share This<\/h4>\n<h4><\/h5><ul class='av-share-box-list noLightbox'><li class='av-share-link av-social-link-facebook' ><a target=\"_blank\" aria-label=\"Teilen auf Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/&amp;t=Kuvana%20jela\" aria-hidden=\"false\" data-av_icon=\"\ue8f3\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Teilen auf Facebook\" rel=\"noopener\"><span class='avia_hidden_link_text'>Teilen auf Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target=\"_blank\" aria-label=\"Teilen auf Twitter\" href=\"https:\/\/twitter.com\/share?text=Kuvana%20jela&amp;url=https:\/\/titandizajn.com\/de\/?p=4041\" aria-hidden=\"false\" data-av_icon=\"\ue8f1\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Teilen auf Twitter\" rel=\"noopener\"><span class='avia_hidden_link_text'>Teilen auf Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-whatsapp' ><a target=\"_blank\" aria-label=\"Teilen auf WhatsApp\" href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/\" aria-hidden=\"false\" data-av_icon=\"\uf232\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Teilen auf WhatsApp\" rel=\"noopener\"><span class='avia_hidden_link_text'>Teilen auf WhatsApp<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin' ><a target=\"_blank\" aria-label=\"Teilen auf LinkedIn\" href=\"https:\/\/linkedin.com\/shareArticle?mini=true&amp;title=Kuvana%20jela&amp;url=https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/\" aria-hidden=\"false\" data-av_icon=\"\ue8fc\" data-av_iconfont=\"entypo-fontello\" title=\"\" data-avia-related-tooltip=\"Teilen auf LinkedIn\" rel=\"noopener\"><span class='avia_hidden_link_text'>Teilen auf LinkedIn<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  aria-label=\"Per E-Mail teilen\" href='mailto:?subject=Kuvana%20jela&#038;body=https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/' aria-hidden='false' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Per E-Mail teilen'><span class='avia_hidden_link_text'>Per E-Mail teilen<\/span><\/a><\/li><\/ul><\/div><\/div><\/div><\/h4>\n<div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding   avia-builder-el-8  el_after_av_one_third  avia-builder-el-last  \" style='border-radius:0px; '><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":23601,"comment_status":"open","ping_status":"open","template":"","tags":[],"portfolio_entries":[132],"class_list":["post-4041","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-verpackungs-design"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kuvana jela - Titan Dizajn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kuvana jela - Titan Dizajn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/\" \/>\n<meta property=\"og:site_name\" content=\"Titan Dizajn\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-12T07:35:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/10\/dizajn-ambalaze-gotova-jela-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/\",\"name\":\"Kuvana jela - Titan Dizajn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dizajn-ambalaze-gotova-jela-1.webp\",\"datePublished\":\"2019-12-20T09:49:30+00:00\",\"dateModified\":\"2023-10-12T07:35:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dizajn-ambalaze-gotova-jela-1.webp\",\"contentUrl\":\"https:\\\/\\\/titandizajn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/dizajn-ambalaze-gotova-jela-1.webp\",\"width\":480,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/portfolio\\\/kuvana-jela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna\",\"item\":\"https:\\\/\\\/titandizajn.com\\\/de\\\/pocetna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kuvana jela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/titandizajn.com\\\/#website\",\"url\":\"https:\\\/\\\/titandizajn.com\\\/\",\"name\":\"Titan Dizajn\",\"description\":\"Creative Agency\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/titandizajn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kuvana jela - Titan Dizajn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/","og_locale":"de_DE","og_type":"article","og_title":"Kuvana jela - Titan Dizajn","og_url":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/","og_site_name":"Titan Dizajn","article_modified_time":"2023-10-12T07:35:34+00:00","og_image":[{"width":480,"height":435,"url":"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/10\/dizajn-ambalaze-gotova-jela-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/","url":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/","name":"Kuvana jela - Titan Dizajn","isPartOf":{"@id":"https:\/\/titandizajn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/#primaryimage"},"image":{"@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/#primaryimage"},"thumbnailUrl":"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/10\/dizajn-ambalaze-gotova-jela-1.webp","datePublished":"2019-12-20T09:49:30+00:00","dateModified":"2023-10-12T07:35:34+00:00","breadcrumb":{"@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/#primaryimage","url":"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/10\/dizajn-ambalaze-gotova-jela-1.webp","contentUrl":"https:\/\/titandizajn.com\/wp-content\/uploads\/2023\/10\/dizajn-ambalaze-gotova-jela-1.webp","width":480,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/titandizajn.com\/de\/portfolio\/kuvana-jela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna","item":"https:\/\/titandizajn.com\/de\/pocetna\/"},{"@type":"ListItem","position":2,"name":"Kuvana jela"}]},{"@type":"WebSite","@id":"https:\/\/titandizajn.com\/#website","url":"https:\/\/titandizajn.com\/","name":"Titan Dizajn","description":"Creative Agency","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/titandizajn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/portfolio\/4041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/comments?post=4041"}],"version-history":[{"count":3,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/portfolio\/4041\/revisions"}],"predecessor-version":[{"id":24089,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/portfolio\/4041\/revisions\/24089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/media\/23601"}],"wp:attachment":[{"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/media?parent=4041"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/tags?post=4041"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/titandizajn.com\/de\/wp-json\/wp\/v2\/portfolio_entries?post=4041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}